{"id":10571,"date":"2026-03-21T11:55:55","date_gmt":"2026-03-21T10:55:55","guid":{"rendered":"https:\/\/sumitraimport.com\/product\/cotton-tunic-3\/"},"modified":"2026-04-09T17:46:53","modified_gmt":"2026-04-09T16:46:53","slug":"cotton-tunic-3","status":"publish","type":"product","link":"https:\/\/sumitraimport.com\/fr\/produit\/cotton-tunic-3\/","title":{"rendered":"TUNIQUE EN COTON"},"content":{"rendered":"<p>Robe-chemise longueur genou, boutonn\u00e9e sur le devant, d\u00e9collet\u00e9 en V sans col et manches trois-quarts. Le tissu est l\u00e9ger, probablement un m\u00e9lange de coton ou de lin, d\u00e9cor\u00e9 d'un imprim\u00e9 tropical vibrant comprenant des palmiers, des motifs floraux, des fruits et des sc\u00e8nes de plage. Des mots tels que \u2018 Sun &amp; Beach \u2019 (soleil et plage) sont incorpor\u00e9s dans le motif. Couleur de base bleu aqua vif avec imprim\u00e9 tropical multicolore.<\/p>\n<p>- Tissu : Coton<br \/>\n- Couleurs disponibles : Multi<br \/>\n- Taille : Taille libre (taille unique)<br \/>\n- Emballage de : 6 pi\u00e8ces<\/p>\n<p>Cat\u00e9gorie : Tunique, Robe courte<br \/>\nTags : Tunique, Multicolore, Imprim\u00e9, Robe de plage<\/p>","protected":false},"excerpt":{"rendered":"<p>6<\/p>\n<table class=\"ptable\">\n<tbody>\n<tr>\n<td>Pack-of \u27a0<\/td>\n<td>6<\/td>\n<\/tr>\n<tr>\n<td>Couleur \u27a0<\/td>\n<td>MULTI,La VISCOSE EMBROIDERY TYE DYE LONG DRESS est un produit \u00e9l\u00e9gant et polyvalent fabriqu\u00e9 \u00e0 partir de viscose de haute qualit\u00e9. Elle est disponible dans une couleur MULTI et dans des tailles comme FREE. Ce produit est parfait pour toutes les occasions, et il est disponible en paquet de 12. Tags : viscose, tye dye, broderie, robe longue.<\/td>\n<\/tr>\n<tr>\n<td>Tissu \u27a0<\/td>\n<td>COTON<\/td>\n<\/tr>\n<tr>\n<td>Taille \u27a0<\/td>\n<td>GRATUIT<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"featured_media":10572,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_angie_page":false,"uix_meta_title":"","uix_meta_description":"","uix_canonical_url":""},"product_brand":[],"product_cat":[70,242],"product_tag":[237,236,285,80,219],"class_list":["post-10571","product","type-product","status-publish","has-post-thumbnail","product_cat-short-dress","product_cat-tunic-top","product_tag-beach-dress","product_tag-multi-colour","product_tag-ofl","product_tag-printed","product_tag-tunic","pa_pack-of-161","pa_sizes-free","first","outofstock","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/product\/10571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/comments?post=10571"}],"version-history":[{"count":0,"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/product\/10571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/media\/10572"}],"wp:attachment":[{"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/media?parent=10571"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/product_brand?post=10571"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/product_cat?post=10571"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sumitraimport.com\/fr\/wp-json\/wp\/v2\/product_tag?post=10571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}